{"id":2081,"date":"2019-12-23T11:10:50","date_gmt":"2019-12-23T11:10:50","guid":{"rendered":"https:\/\/jobs.nokriwp.com\/?page_id=1469"},"modified":"2019-12-23T11:10:50","modified_gmt":"2019-12-23T11:10:50","slug":"capricio-demo","status":"publish","type":"page","link":"https:\/\/elementor.nokriwp.com\/demo-3\/capricio-demo\/","title":{"rendered":"Capricio Demo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2081\" class=\"elementor elementor-2081\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-0e60ecb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0e60ecb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-453e5bd\" data-id=\"453e5bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c066591 elementor-widget elementor-widget-hero-section3\" data-id=\"c066591\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hero-section3.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"n-hero-8\"  style=\"background:  url(https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/clouds.png) no-repeat scroll center center \/ cover;\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-lg-12 col-sm-12 col-md-12 col-xs-12\">\n\t\t\t\t\t\t<div class=\"n-8-container\">\n\t\t\t\t\t\t<div class=\"n-8-content\">\n\t\t\t\t\t\t <h1>We Offer <span class=\"heading-color\">25,000<\/span>Job Vacancies Right Now!<\/h1>\n                         <p>The most complete field service software for IT & Mobile Support, Fire Services, Electrical, Maintenance, HVAC & Security Industries<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"n-8-product\">\n\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t<a  href=\"# \"  target=\"_blank\" class=\"btn n-btn-flat\"> Job Apply <\/a>\n\t\t\t\t\t\t\t<li><a class=\"hero-video\" href=\"https:\/\/www.youtube.com\/watch?v=3qyhgV0Zew0\"><i class=\"fa fa-play\"><\/i> <span>Click To Watch<\/span> <\/a> <\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"n-8-employs\"> <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/employs.png\" alt=\"image\"\/><\/div>\n\t\t\t\t\t\t<div class=\"n-8-serch-field\">\n\t\t\t\t\t\t<form   method=\"get\" action=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidates\/\">\n\t\t\t\t\t\t      \n\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"form-group\">\n\t\t\t\t\t\t\t\t<label>Search Keyword<\/label>\n\t\t\t\t\t\t\t\t<input type=\"text\" class=\"form-control\" name=\"cand_title\" placeholder=\"Search here\"\/>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"form-group\">\n\t\t\t\t\t\t\t\t<label>Search Categories<\/label>\n\t\t\t\t\t\t\t\t<select class=\"js-example-basic-single form-control\" data-allow-clear=\"true\" data-placeholder=\"Select Category\"    name=\"cand_skills\">\n\t\t\t\t\t\t\t\t   <option label=\"Select Category\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"80\">Automotive   (1)<\/option><option value=\"88\">Construction   (0)<\/option><option value=\"18\">Consultant   (1)<\/option><option value=\"11\">Customer Service   (1)<\/option><option value=\"8\">Designer   (2)<\/option><option value=\"204\">Development   (1)<\/option><option value=\"84\">Digital Service   (1)<\/option><option value=\"83\">Education   (0)<\/option><option value=\"13\">Engineering   (1)<\/option><option value=\"16\">Fitness Trainer   (1)<\/option><option value=\"86\">Food Service   (1)<\/option><option value=\"81\">Health and Care   (2)<\/option><option value=\"15\">HR   (0)<\/option><option value=\"12\">Human Resource   (1)<\/option><option value=\"79\">Industry   (0)<\/option><option value=\"9\">Information Technology   (1)<\/option><option value=\"10\">Marketing   (0)<\/option><option value=\"17\">Networking   (0)<\/option><option value=\"85\">Other Services   (0)<\/option><option value=\"14\">Security   (0)<\/option><option value=\"87\">Web Designer   (1)<\/option><option value=\"82\">Web Development   (0)<\/option>\n\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"form-group\">\n\t\t\t\t\t\t\t\t<label>Search Location<\/label>\n\t\t\t\t\t\t\t\t<select class=\"js-example-basic-single form-control\" data-allow-clear=\"true\" data-placeholder=\"Select Location\"  name=\"job-location\">\n\t\t\t\t\t\t\t\t   <option value=\"\">Select Location<\/option>\n\t\t\t\t\t\t\t\t\t <option value=\"116\">Australia   (6)<\/option><option value=\"76\">Germany   (5)<\/option><option value=\"70\">India   (1)<\/option><option value=\"72\">New delhi   (0)<\/option><option value=\"132\">Pakistan   (2)<\/option><option value=\"73\">UAE   (0)<\/option><option value=\"66\">USA   (1)<\/option>\n\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"\"> \n\t\t\t\t\t\t\t\t\t<button type=\"submit\" class=\"btn n-btn-flat\">Search<\/button>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>                <script>\n                    (function($) {\n                        function initSelect2_c066591() {\n                            var $selects = $('[data-id=\"c066591\"]').find('.js-example-basic-single');\n                            if ($selects.length && $.fn.select2) {\n                                $selects.select2({\n                                    allowClear: true,\n                                    maximumSelectionLength: 8,\n                                    language: {\n                                        noResults: function(params) {\n                                            return (typeof get_strings !== 'undefined') ? get_strings.no_res : 'No results found';\n                                        },\n                                        maximumSelected: function(e) {\n                                            return (typeof get_strings !== 'undefined') ? get_strings.max_select + e.maximum : 'You can only select ' + e.maximum + ' items';\n                                        }\n                                    }\n                                });\n                            }\n                        }\n\n                        if (window.elementorFrontend) {\n                            initSelect2_c066591();\n                        } else {\n                            $(document).ready(function() {\n                                initSelect2_c066591();\n                            });\n                        }\n                    })(jQuery);\n                <\/script>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-3110f18 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3110f18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-946e8c0\" data-id=\"946e8c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3afc28 elementor-widget elementor-widget-preminum-jobs_tab2\" data-id=\"e3afc28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"preminum-jobs_tab2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class = \"n-jobs-recomend3 space3\">\n                            <div class = \"container\">\n                            <div class = \"row clear-custom\">\n                            <div class = \"col-lg-12 col-xs-12 col-sm-12 col-md-12\">\n                                <div class = \"n-listing-text-wrapper\">\n                                    <div class = \"n-listing-text\">\n                                    <h2>Recommended Jobs<\/h2>\n                                    <p>Browse personalized job recommendations selected just for you.<\/p><\/div>\n                                    <ul class = \"nav nav-tabs\">\n                                    <li><a class=\"active\" data-bs-toggle=\"tab\" href=\"#home1\">Feature<\/a><\/li><li><a class=\"\" data-bs-toggle=\"tab\" href=\"#home2\">Urgent<\/a><\/li><li><a class=\"\" data-bs-toggle=\"tab\" href=\"#home3\">Private<\/a><\/li>\n                                    <\/ul>\n                                <\/div>\n                            <div class = \"tab-content\">\n                            <div id=\"home1\" class=\"tab-pane fade show active\">\n\t\t\t\t\t\t\t\t  <div class=\"row\">\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/job_category\/information-technology\/\">Information Technology<\/a><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/network-assistant-manager-2\/\">\n                            <div class = \"jobs3-style\">Network Assistant Manager<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 10 months ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/germany\/\"> Germany<\/a><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/job_category\/designer\/\">Designer<\/a><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/creative-graphic-designer\/\">\n                            <div class = \"jobs3-style\">Creative Graphic Designer<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 months ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/victoria\/\"> Victoria<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/australia\/\"> Australia<\/a><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/job_category\/automotive\/\">Automotive<\/a><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/automotive-service-technician\/\">\n                            <div class = \"jobs3-style\">Automotive Service Technician<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 months ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/frankfurt\/\"> Frankfurt<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/berlin\/\"> Berlin<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/germany\/\"> Germany<\/a><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/job_category\/customer-service\/\">Customer Service<\/a><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/customer-service-representative-4\/\">\n                            <div class = \"jobs3-style\">Customer Service Representative<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 months ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/frankfurt\/\"> Frankfurt<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/berlin\/\"> Berlin<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/germany\/\"> Germany<\/a><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div><div class=\"col-lg-12 col-xs-12 col-sm-12 col-md-12\"><div class=\"n-jobs3-product\"><a  href=\"# \"  target=\"_blank\" class=\"btn n-btn-flat\"> View More <\/a><\/div><\/div><\/div><\/div><div id=\"home2\" class=\"tab-pane fade \">\n\t\t\t\t\t\t\t\t  <div class=\"row\">\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/casual-bartender\/\">\n                            <div class = \"jobs3-style\">Casual Bartender<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 years ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/casual-server\/\">\n                            <div class = \"jobs3-style\">Casual Server<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 years ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/job_category\/digital-service\/\">Digital Service<\/a><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/data-entry-clerk-work-from-home-2\/\">\n                            <div class = \"jobs3-style\">Data Entry Clerk &#8211; Work from Home<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 11 months ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/usa\/\"> USA<\/a><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div><div class=\"col-lg-12 col-xs-12 col-sm-12 col-md-12\"><div class=\"n-jobs3-product\"><a  href=\"# \"  target=\"_blank\" class=\"btn n-btn-flat\"> View More <\/a><\/div><\/div><\/div><\/div><div id=\"home3\" class=\"tab-pane fade \">\n\t\t\t\t\t\t\t\t  <div class=\"row\">\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/job_category\/engineering\/\">Engineering<\/a><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/boq-officer\/\">\n                            <div class = \"jobs3-style\">Boq officer<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 years ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/model-town\/\"> Model Town<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/lahore\/\"> Lahore<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/punjab\/\"> Punjab<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/pakistan\/\"> Pakistan<\/a><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/casual-bartender\/\">\n                            <div class = \"jobs3-style\">Casual Bartender<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 years ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/casual-server\/\">\n                            <div class = \"jobs3-style\">Casual Server<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 years ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/job_category\/health-and-care\/\">Health and Care<\/a><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/sterilization-technician-2\/\">\n                            <div class = \"jobs3-style\">Sterilization Technician<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 10 months ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/pakistan\/\"> Pakistan<\/a><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                                <div class = \"col-lg-4 col-sm-6 col-md-6 col-xs-12\">\n                            <div class = \"n-jobs3-container\">\n                            <div class = \"n-jobs3-categories\">\n                            <img src = \"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt = \"image\" class = \"img-responsive\"\/>\n                            <div class = \"n-jobs3-categories-2\">\n                            <span><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/job_category\/consultant\/\">Consultant<\/a><\/span>\n                            <a href = \"https:\/\/elementor.nokriwp.com\/demo-3\/job\/business-strategy-consultant\/\">\n                            <div class = \"jobs3-style\">Business Strategy Consultant<\/div>\n                            <\/a>\n                            <p><i class = \"fa fa-clock-o\"><\/i> 6 months ago<\/p>\n                            <\/div>\n                            <\/div>\n                            <div class = \"n-jobs3-content\">\n                            <p><i class = \"fa fa-map-marker\"><\/i><a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/frankfurt\/\"> Frankfurt<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/berlin\/\"> Berlin<\/a>,<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/ad_location\/germany\/\"> Germany<\/a><\/p>\n                            <\/div>\n                            <\/div>\n                            <\/div><div class=\"col-lg-12 col-xs-12 col-sm-12 col-md-12\"><div class=\"n-jobs3-product\"><a  href=\"# \"  target=\"_blank\" class=\"btn n-btn-flat\"> View More <\/a><\/div><\/div><\/div><\/div>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                            <\/div>\n                            <\/section>\n\n                            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-8382fee elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8382fee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ea607e\" data-id=\"7ea607e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa11c80 elementor-widget elementor-widget-call-to-action4\" data-id=\"fa11c80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action4.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"n-callto-action-8\"  style=\"background: url(https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/sr.png) center center no-repeat; -webkit-background-size: cover; -moz-background-size: cover; -o-background-size: cover; background-size: cover; background-position: center center; background-attachment:scroll;\"> \n\t\t\t<div class=\"container\">\n\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-lg-6 col-sm-12 col-md-12 col-xs-12\">\n\t\t\t\t<div class=\"n-callto-details\">\n\t\t\t\t\t<span>Millions of Jobs<\/span>\n\t\t\t\t\t<h3>Find the one that\u2019s Right for you<\/h3>\n\t\t\t\t\t<p>Explore thousands of job opportunities across various industries and locations. Discover roles that match your skills, experience, and career goals, and take the next step toward a brighter future with confidence.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<ul>\n\t\t\t\t\t<li> \n\t\t\t\t\t\t\t\t\t<div class=\"counter-js\">\n\t\t\t\t\t\t\t\t\t<span class=\"counter\" data-to=\"6600\" data-time=\"2000\" data-fps=\"20\"><\/span>\n\t\t\t\t\t\t\t\t\t <p>Jobs everyday<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/li><li> \n\t\t\t\t\t\t\t\t\t<div class=\"counter-js\">\n\t\t\t\t\t\t\t\t\t<span class=\"counter\" data-to=\"6600\" data-time=\"2000\" data-fps=\"20\"><\/span>\n\t\t\t\t\t\t\t\t\t <p>Website Served<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/li><li> \n\t\t\t\t\t\t\t\t\t<div class=\"counter-js\">\n\t\t\t\t\t\t\t\t\t<span class=\"counter\" data-to=\"6600\" data-time=\"2000\" data-fps=\"20\"><\/span>\n\t\t\t\t\t\t\t\t\t <p>Sucessful Hiring<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-lg-6 col-sm-12 col-md-12 col-xs-12\"><div class=\"n-8-img\"><img decoding=\"async\" src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2026\/02\/sr-1.png\" alt=\"image\" class=\"img-responsive\"\/><\/div><\/div>\n\t\t\t  <\/div>\n\t\t\t<\/div>\n\t\t\t<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-e7539bd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e7539bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8ba3ef\" data-id=\"a8ba3ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef2d294 elementor-widget elementor-widget-featured_candidates_3\" data-id=\"ef2d294\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"featured_candidates_3.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"n-f-candidates4 space2\">\n\t\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-lg-12 col-xs-12 col-sm-12 col-md-12\"> \n\t\t\t<div class=\"heading-penel\">\n\t\t\t\t<h3>Feature Candidates<\/h3>\n\t\t\t\t<p>Explore top-rated and highly skilled candidates ready to contribute to your organization.<\/p>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"col-lg-4 col-xs-12 col-sm-6 col-md-6\">\n\t\t\t\t\t\t\t\t\t<div class=\"n-f-canidates-content\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/lina-vogel-de\/\"><img decoding=\"async\" src=\"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt=\"image\" class=\"img-responsive\"\/><\/a>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/lina-vogel-de\/\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"n-f-style\">\n\t\t\t\t\t\t\t\t\t\tLina Vogel\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<p>Data Analyst<\/p>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/lina-vogel-de\/\" class=\"btn n-btn-flat\">View Profile<\/a>\n\t\t\t\t\t\t\t\t\t<div class=\"n-candidates-style\">\n\t\t\t\t\t\t\t\t\t<a href=\"javascript:void(0)\" class=\"saving_resume\" data-cand-id=\"1489\"><i class=\"fa fa-heart-o\"><\/i><\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"features-star\"><i class=\"fa fa-star\"><\/i><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-xs-12 col-sm-6 col-md-6\">\n\t\t\t\t\t\t\t\t\t<div class=\"n-f-canidates-content\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/harper-collins-us\/\"><img decoding=\"async\" src=\"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt=\"image\" class=\"img-responsive\"\/><\/a>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/harper-collins-us\/\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"n-f-style\">\n\t\t\t\t\t\t\t\t\t\tHarper Collins\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<p>UI\/UX Designer<\/p>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/harper-collins-us\/\" class=\"btn n-btn-flat\">View Profile<\/a>\n\t\t\t\t\t\t\t\t\t<div class=\"n-candidates-style\">\n\t\t\t\t\t\t\t\t\t<a href=\"javascript:void(0)\" class=\"saving_resume\" data-cand-id=\"1488\"><i class=\"fa fa-heart-o\"><\/i><\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"features-star\"><i class=\"fa fa-star\"><\/i><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-xs-12 col-sm-6 col-md-6\">\n\t\t\t\t\t\t\t\t\t<div class=\"n-f-canidates-content\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/ava-mitchell-au\/\"><img decoding=\"async\" src=\"https:\/\/demo.nokriwp.com\/wp-content\/themes\/nokri\/images\/candidate-dp.jpg\" alt=\"image\" class=\"img-responsive\"\/><\/a>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/ava-mitchell-au\/\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"n-f-style\">\n\t\t\t\t\t\t\t\t\t\tAva Mitchell\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<p>Digital Marketing Manager<\/p>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/candidate\/ava-mitchell-au\/\" class=\"btn n-btn-flat\">View Profile<\/a>\n\t\t\t\t\t\t\t\t\t<div class=\"n-candidates-style\">\n\t\t\t\t\t\t\t\t\t<a href=\"javascript:void(0)\" class=\"saving_resume\" data-cand-id=\"1487\"><i class=\"fa fa-heart-o\"><\/i><\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"features-star\"><i class=\"fa fa-star\"><\/i><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><div class=\"clearfix\"><\/div>\n\t\t\t<\/div>\n  \t\t<\/div>\n\t<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-eadeac8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"eadeac8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e34192\" data-id=\"8e34192\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecfda51 elementor-widget elementor-widget-cand-emp-section1\" data-id=\"ecfda51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cand-emp-section1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"nth-success n-padding-bottom\">\n\t\t\t<div class=\"container\">\n\t\t\t\t<div class=\"row nth-sc-product\">\n\t\t\t\t\t<div class=\"col-lg-6 col-sm-12 col-md-6 col-xs-12\">\n\t\t\t\t\t\t<div class=\"nth-sc-content\"  style=\"background:  url(https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/re.png) center center no-repeat; -webkit-background-size: cover; -moz-background-size: cover; -o-background-size: cover; background-size: cover;\">\n\t\t\t\t\t\t <h3>I'm an Employer<\/h3>\n\t\t\t\t\t\t <p>Post jobs, manage applications, and connect with qualified candidates to build your team faster.<\/p>\n\t\t\t\t\t\t<a  href=\"# \"  target=\"_blank\" class=\"btn n-btn-flat btn-mid\"> View All Jobs <\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-lg-6 col-sm-12 col-md-6 col-xs-12\">\n\t\t\t\t\t\t<div class=\"nth-sc-content-2 nth-sc-content\"  style=\"background: url(https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/re-1.png) center center no-repeat; -webkit-background-size: cover; -moz-background-size: cover; -o-background-size: cover; background-size: cover;\">\n\t\t\t\t\t\t<h3>I'm an Candidates<\/h3>\n\t\t\t\t\t\t<p>Create your profile, upload your resume, and apply for jobs that match your skills and career goals.<\/p>\n\t\t\t\t\t\t<a  href=\"# \"  target=\"_blank\" class=\"btn n-btn-flat btn-mid\"> View All Jobs <\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-dd6e919 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dd6e919\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dd5f2a\" data-id=\"9dd5f2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2dff16 elementor-widget elementor-widget-success_stories1\" data-id=\"f2dff16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"success_stories1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"nth-success-products \">\n\t\t\t<div class=\"container\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-lg-12\">\n\t\t\t\t\t\t<div class=\"heading-penel\">\n\t\t\t\t\t\t\t<h3>Success Our Stories<\/h3>\n\t\t\t\t\t\t\t<p>Discover real success stories from professionals and companies who achieved their goals with us.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"success1-slider owl-carousel owl-theme\">\n\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t<div class=\"nth-sc-box\">\n\t\t\t\t\t\t\t\t\t<p>Read real stories of career growth and successful hiring experiences shared by our community.<\/p>\n\t\t\t\t\t\t\t\t\t\t<div class=\"nth-sc-profile\"><img decoding=\"async\"  src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/65.png\" class=\"img-responsive\" alt=\"image\"\/><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"nth-sc-details\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-profile-text\">Effay Khan<\/div>\n\t\t\t\t\t\t\t\t\t\t\t <p>Software Engineer<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"nth-image-bg\"><img decoding=\"async\"  src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/fc.png\" class=\"img-responsive\" alt=\"image\"\/><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"item\">\n\t\t\t\t\t\t\t\t<div class=\"nth-sc-box\">\n\t\t\t\t\t\t\t\t\t<p>Explore how professionals found dream jobs and companies built strong teams with our support.<\/p>\n\t\t\t\t\t\t\t\t\t\t<div class=\"nth-sc-profile\"><img decoding=\"async\"  src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/65.png\" class=\"img-responsive\" alt=\"image\"\/><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"nth-sc-details\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-profile-text\">Effay Khan<\/div>\n\t\t\t\t\t\t\t\t\t\t\t <p>Software Engineer<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"nth-image-bg\"><img decoding=\"async\"  src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/fc.png\" class=\"img-responsive\" alt=\"image\"\/><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"item\">\n\t\t\t\t\t\t\t\t<div class=\"nth-sc-box\">\n\t\t\t\t\t\t\t\t\t<p>Discover inspiring journeys of candidates and employers who achieved their goals through our platform.<\/p>\n\t\t\t\t\t\t\t\t\t\t<div class=\"nth-sc-profile\"><img decoding=\"async\"  src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/65.png\" class=\"img-responsive\" alt=\"image\"\/><\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"nth-sc-details\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-profile-text\">Effay Khan<\/div>\n\t\t\t\t\t\t\t\t\t\t\t <p>Software Engineer<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"nth-image-bg\"><img decoding=\"async\"  src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/fc.png\" class=\"img-responsive\" alt=\"image\"\/><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/section>                <script>\n                (function($) {\n                    function initHiringSlider_f2dff16() {\n                        var $slider = $('[data-id=\"f2dff16\"]').find('.success1-slider');\n                        if (!$slider.length) return;\n                        if ($slider.hasClass('owl-loaded')) {\n                            $slider.trigger('destroy.owl.carousel');\n                            $slider.find('.owl-stage-outer').children().unwrap();\n                            $slider.find('.owl-dots, .owl-nav').remove();\n                            $slider.removeClass('owl-loaded owl-hidden');\n                        }\n                        $slider.owlCarousel({\n                            loop: true,\n                            margin: 24,\n                            autoplay: true,\n                            nav: true,\n                            rtl: false,\n                            responsive: {\n                              0: {\n                                items: 1,\n                              },\n                              768: {\n                                items: 2,\n                              },\n                              992: {\n                                items: 3,\n                              },\n                              1000: {\n                                items: 3,\n                              },\n                            },\n                        });\n                    }\n\n                    if (window.elementorFrontend) {\n                        initHiringSlider_f2dff16();\n                    } else {\n                        $(document).ready(function() {\n                            initHiringSlider_f2dff16();\n                        });\n                    }\n                })(jQuery);\n                <\/script>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc88ac0 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bc88ac0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd2e2c8\" data-id=\"bd2e2c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-075b540 elementor-widget elementor-widget-blog_post_modern\" data-id=\"075b540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blog_post_modern.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"nth-latest-update nth-latest2 nth-latest3\">\n\t\t\t<div class=\"container\">\n\t\t\t<div class=\"row\">\n\t\t\t     <div class=\"col-lg-12 col-md-12 col-sm-12\">\r\n                            <div class=\"heading-title black\">\r\n                                <h2>Latest News<\/h2>\r\n                                 <p>Stay updated with the latest industry news, career insights, hiring trends, and platform updates.<\/p>\r\n                            <\/div>\r\n                        <\/div>\n\t\t\t\t <div class=\"col-lg-12 col-md-12 col-sm-12 col-xs-12 \">\n\t\t\t\t\t <div class=\"row\">\n\t\t\t\t\t\t<div class=\"col-lg-4 col-sm-12 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-product\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/career-trends-the-important-skills-youll-need-for-the-jobs-of-the-next-upcoming-years\/\"> <img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"360\" src=\"https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-1068523.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-1068523.jpeg 750w, https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-1068523-300x144.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/> <\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-cb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/career-trends-the-important-skills-youll-need-for-the-jobs-of-the-next-upcoming-years\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4>Career trends: The important skills you\u2019ll need for Job<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-in\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><i class=\"fa fa-comments\"><\/i><span>0<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><i class=\"fa fa-calendar\"><\/i><span>August 29, 2018<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-blog\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-profile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/?s=45&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/?s=90&#038;d=mm&#038;r=g 2x' class='avatar avatar-45 photo avatar-default img-responsive' height='45' width='45' \/> <span class=\"nth-style-0\">nokri<\/span> \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-jobs\"> <i class=\"fa fa-long-arrow-right\" aria-hidden=\"true\"><\/i> \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-sm-12 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-product\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/points-to-consider-before-accepting-a-new-job-offer\/\"> <img decoding=\"async\" width=\"750\" height=\"360\" src=\"https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-1093913.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-1093913.jpeg 750w, https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-1093913-300x144.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/> <\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-cb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/points-to-consider-before-accepting-a-new-job-offer\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4>Tips For Preparing A Elevator Pitch<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-in\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><i class=\"fa fa-comments\"><\/i><span>0<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><i class=\"fa fa-calendar\"><\/i><span>August 29, 2018<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-blog\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-profile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/?s=45&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/?s=90&#038;d=mm&#038;r=g 2x' class='avatar avatar-45 photo avatar-default img-responsive' height='45' width='45' \/> <span class=\"nth-style-0\">nokri<\/span> \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-jobs\"> <i class=\"fa fa-long-arrow-right\" aria-hidden=\"true\"><\/i> \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div><div class=\"col-lg-4 col-sm-12 col-md-6 col-xs-12\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-product\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/tips-for-preparing-an-elevator-speech-that-helps-you-get-hired\/\"> <img decoding=\"async\" width=\"750\" height=\"360\" src=\"https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-630839-1.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-630839-1.jpeg 750w, https:\/\/elementor.nokriwp.com\/demo-3\/wp-content\/uploads\/sites\/9\/2018\/08\/pexels-photo-630839-1-300x144.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/> <\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-cb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/elementor.nokriwp.com\/demo-3\/tips-for-preparing-an-elevator-speech-that-helps-you-get-hired\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4>Points To Consider Before Accepting A New Jon Offer!<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-in\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><i class=\"fa fa-comments\"><\/i><span>0<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><i class=\"fa fa-calendar\"><\/i><span>August 29, 2018<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-blog\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-profile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/?s=45&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/?s=90&#038;d=mm&#038;r=g 2x' class='avatar avatar-45 photo avatar-default img-responsive' height='45' width='45' \/> <span class=\"nth-style-0\">nokri<\/span> \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nth-latest-jobs\"> <i class=\"fa fa-long-arrow-right\" aria-hidden=\"true\"><\/i> \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n  \t\t\t<\/div>\n\t\t<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-797e64d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"797e64d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-433c1b8\" data-id=\"433c1b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a2254e elementor-widget elementor-widget-app_section-modern\" data-id=\"4a2254e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"app_section-modern.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"nth-mob-app mob-apps\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-lg-6 col-sm-12 col-md-6\">\n\t\t\t\t\t<div class=\"nth-mob-details\"  style=\"background: url(https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/gb-1.png); -webkit-background-size: cover; -moz-background-size: cover; -o-background-size: cover; background-size: cover; background-position: center center;   margin-top: 60px;\noverflow: hidden;\">\n\t\t\t\t\t\t<span>Get the Apps Now!<\/span>\n\t\t\t\t\t\t<div class=\"nth-mob-style\">Download our free Mobile Apps Today Get Ready<\/div>\n\t\t\t\t\t\t<p>Download our free mobile app and stay connected wherever you are. Search jobs, apply instantly, manage applications, and receive real-time notifications all from your smartphone.<\/p>\n\t\t\t\t\t\t<div class=\"nth-store-apps\">\n\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t<li class=\"li-ply-str\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/store-1.png\" alt=\"playStore\"\/><\/a><\/li>\n\t\t\t\t\t\t\t\t<li class=\"li-app-str\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/store.png\"  alt=\"AppStore\"\/><\/a><\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-lg-6 col-sm-12 col-md-6\"><div class=\"nth-mob-img\"><img decoding=\"async\" src=\"https:\/\/elementor.nokriwp.com\/wp-content\/uploads\/2019\/12\/mob.png\" class=\"img-responsive\" alt=\"Image\"\/><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>We Offer 25,000Job Vacancies Right Now! The most complete field service software for IT &amp; Mobile Support, Fire Services, Electrical, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-home.php","meta":{"footnotes":""},"class_list":["post-2081","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/elementor.nokriwp.com\/demo-3\/wp-json\/wp\/v2\/pages\/2081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elementor.nokriwp.com\/demo-3\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elementor.nokriwp.com\/demo-3\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elementor.nokriwp.com\/demo-3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elementor.nokriwp.com\/demo-3\/wp-json\/wp\/v2\/comments?post=2081"}],"version-history":[{"count":0,"href":"https:\/\/elementor.nokriwp.com\/demo-3\/wp-json\/wp\/v2\/pages\/2081\/revisions"}],"wp:attachment":[{"href":"https:\/\/elementor.nokriwp.com\/demo-3\/wp-json\/wp\/v2\/media?parent=2081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}